{"id":11311,"date":"2021-03-09T11:08:59","date_gmt":"2021-03-09T03:08:59","guid":{"rendered":"https:\/\/seppeschina.com\/?p=11311"},"modified":"2021-03-12T10:47:49","modified_gmt":"2021-03-12T02:47:49","slug":"la-porte-rapide-a-enroulement-can-seppes-peut-elle-controler-louverture-et-la-fermeture-du-rideau-dair","status":"publish","type":"post","link":"https:\/\/seppeschina.com\/fr\/blog\/can-seppes-fast-rolling-door-control-the-opening-and-closing-of-the-air-curtain\/","title":{"rendered":"La porte \u00e0 enroulement rapide Seppes peut-elle contr\u00f4ler l'ouverture et la fermeture du rideau d'air ?"},"content":{"rendered":"<p style=\"font-size:20px\">Dans de nombreux endroits, les portes rapides et les rideaux d'air coexistent en tant que partenaires. Les caract\u00e9ristiques communes de ces deux produits sont : l'isolation thermique, la protection contre la poussi\u00e8re et la pr\u00e9vention des insectes, mais leurs principes de fonctionnement sont tr\u00e8s diff\u00e9rents. Seppes peut contr\u00f4ler l'\u00e9tat d'ouverture et de fermeture du rideau d'air lorsque la porte rapide est en fonctionnement, afin de coop\u00e9rer mutuellement pour maintenir l'atelier dans un \u00e9tat de temp\u00e9rature constante et de propret\u00e9, tout en permettant \u00e9galement d'\u00e9conomiser de l'\u00e9nergie.<\/p>\n\n\n\n<p style=\"font-size:20px\">L'image ci-dessous est une prise r\u00e9elle du cas d'utilisation de la porte rapide Seppes et de l'interrupteur de liaison du rideau d'air.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8.jpg\" alt=\"\" class=\"wp-image-11312\" width=\"839\" height=\"559\" srcset=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8.jpg 600w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8-360x240.jpg 360w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8-300x200.jpg 300w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8-128x84.jpg 128w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e8-550x367.jpg 550w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<p style=\"font-size:20px\">Gr\u00e2ce aux avantages de l'interrupteur \u00e0 d\u00e9tection automatique et d'un fonctionnement rapide et fr\u00e9quent, la porte rapide offre un effet de s\u00e9paration dans le couloir logistique, \u00e9vitant les pertes de temp\u00e9rature int\u00e9rieure et bloquant \u00e9galement l'entr\u00e9e de la poussi\u00e8re et des moustiques ext\u00e9rieurs, tout en ne retardant pas les entr\u00e9es et sorties fr\u00e9quentes des chariots \u00e9l\u00e9vateurs et du personnel chaque jour. Le rideau d'air est entra\u00een\u00e9 par un moteur \u00e0 grande vitesse qui actionne le puissant flux d'air g\u00e9n\u00e9r\u00e9 par la roue \u00e0 flux traversant ou centrifuge, formant ainsi un rideau de porte invisible. Le rideau d'air peut s\u00e9parer l'air int\u00e9rieur et ext\u00e9rieur pour emp\u00eacher l'\u00e9change d'air chaud et froid entre l'int\u00e9rieur et l'ext\u00e9rieur, et poss\u00e8de des fonctions de protection contre la poussi\u00e8re, la pollution et les moustiques.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81.jpg\" alt=\"\" class=\"wp-image-11313\" width=\"839\" height=\"733\" srcset=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81.jpg 687w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81-360x314.jpg 360w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81-600x524.jpg 600w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81-300x262.jpg 300w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/03\/\u98ce\u5e55\u673a\u5feb\u901f\u95e81-550x480.jpg 550w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<p style=\"font-size:20px\">Si seul le rideau d'air est utilis\u00e9 dans le couloir logistique, et que le rideau d'air est uniquement utilis\u00e9 pour un soufflage continu, cela entra\u00eene d'une part une consommation d'\u00e9nergie \u00e9lev\u00e9e, et d'autre part, le rideau d'air invisible a un effet limit\u00e9 en mati\u00e8re de temp\u00e9rature et de protection contre la poussi\u00e8re. L'utilisation de portes rapides offre naturellement une tr\u00e8s bonne protection contre la temp\u00e9rature et la poussi\u00e8re, mais lorsque les chariots \u00e9l\u00e9vateurs et le personnel entrent et sortent, la porte \u00e9tant en position ouverte, cet effet n'est pas assur\u00e9. C'est pourquoi les deux sont utilis\u00e9s ensemble. Lorsqu'une personne traverse le passage et que la porte rapide est ouverte, le rideau d'air commence \u00e0 souffler ; lorsque la porte rapide est ferm\u00e9e, le rideau d'air se ferme. L'ouverture et la fermeture du rideau d'air sont contr\u00f4l\u00e9es par la porte rapide, ce qui permet d'\u00e9conomiser au maximum l'\u00e9nergie tout en offrant le meilleur effet de protection contre la poussi\u00e8re.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1.png\" alt=\"\" class=\"wp-image-11035\" width=\"841\" height=\"237\" srcset=\"https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1.png 700w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1-360x101.png 360w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1-600x169.png 600w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1-300x84.png 300w, https:\/\/seppeschina.com\/wp-content\/uploads\/2021\/01\/\u5fae\u4fe1\u56fe\u7247_20201107143544-1-550x155.png 550w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1555-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1555\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/11311#wpcf7-f1555-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/posts\/11311#wpcf7-f1555-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1555\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1555-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"hunkcf71\">\n\t<p class=\"cf7-title\" style=\"font-size:25px;\"><i class=\"fa fa-envelope-o\"><\/i> Nous r\u00e9pondrons \u00e0 votre e-mail sous peu !\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-737\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre nom*\" value=\"\" type=\"text\" name=\"text-737\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-193\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adresse e-mail*\" value=\"\" type=\"email\" name=\"email-193\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-738\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" value=\"\" type=\"text\" name=\"text-738\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-837\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"D\u00e9crivez-nous vos besoins de mani\u00e8re aussi pr\u00e9cise que possible*\" name=\"textarea-837\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>In many places, fast rolling doors and air curtains exist as partners. The common features of these two products are: temperature insulation, dust prevention, and insect prevention, but the principles are quite different. Seppes can control the opening and closing state of the air curtain when the fast rolling door is running, so as to cooperate with each other to keep the workshop in a constant temperature and clean state, and it can also save energy consumption. The picture below is a real shot of the use case of Seppes fast rolling door and air curtain linkage switch Through the advantages of automatic induction switch and fast and frequent operation, the fast rolling door has a partition effect in the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-high-speed-door"],"_links":{"self":[{"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/posts\/11311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/comments?post=11311"}],"version-history":[{"count":2,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/posts\/11311\/revisions"}],"predecessor-version":[{"id":11444,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/posts\/11311\/revisions\/11444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/media\/10995"}],"wp:attachment":[{"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/media?parent=11311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/categories?post=11311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seppeschina.com\/fr\/wp-json\/wp\/v2\/tags?post=11311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}